{"id":4376,"date":"2017-04-18T18:21:25","date_gmt":"2017-04-18T16:21:25","guid":{"rendered":"http:\/\/www.consolvilar.com\/visibilidad-profesional-traves-la-imagen-personal-2\/"},"modified":"2024-04-30T13:04:33","modified_gmt":"2024-04-30T11:04:33","slug":"visibilidad-profesional-traves-la-imagen-personal","status":"publish","type":"post","link":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/","title":{"rendered":"Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials"},"content":{"rendered":"<blockquote>\n<p style=\"text-align: center;\">\u00abUna imatge val m\u00e9s que mil palabras\u00bb<\/p>\n<\/blockquote>\n<p>La majoria de professionals estan en alguna xarxa social, la seva imatge personal \u00e9s observada, valorada i analitzada professionalment segons la xarxa social. Les xarxes socials s\u00f3n un aparador de visibilitat per projectar coneixements, habilitats, compet\u00e8ncies, interessos, etc.<\/p>\n<p>Qu\u00e8 cal saber per treure la m\u00e0xima visibilitat professional a trav\u00e9s de la Imatge personal?<\/p>\n<p><a href=\"http:\/\/www.consolvilar.com\/wp-content\/uploads\/2017\/04\/Visibilidad-profesional-a-trave\u0301s-de-la-imagen-personal.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-4372 aligncenter\" src=\"http:\/\/www.consolvilar.com\/wp-content\/uploads\/2017\/04\/Visibilidad-profesional-a-trave\u0301s-de-la-imagen-personal-300x274.jpg\" alt=\"\" width=\"300\" height=\"274\" \/><\/a><\/p>\n<ol>\n<li>Escollir les xarxes socials amb les quals es volen treballar. Recordeu que no tot professional necessita fer \u00fas de les mateixes xarxes socials, ni projectar-se de la mateixa manera.<\/li>\n<li>Con\u00e8ixer qu\u00e8 comunica la pr\u00f2pia imatge i gestionar-la perqu\u00e8 transmeti i projecti amb efic\u00e0cia segons objectius i identitat. Recorda, tots posse\u00efm una imatge i cal saber-li treure el m\u00e0xim rendiment segons els interessos personals i professionals.<\/li>\n<li>Qualsevol foto, comentari o article exposat, \u00e9s analitzat, valorat i \u00a0a\u00a0vegades\u00a0criticat. Fins i tot hi haur\u00e0 interacci\u00f3 directa.<\/li>\n<li>Privacidad (Viajes, fotos personales de comidas, hijos, etc.) s\u00ed o no? Esto depender\u00e1 de cada persona, no es bueno ni malo. Son estrategias de comunicaci\u00f3n, ser consciente de esto y apostar.<\/li>\n<li>Const\u00e0ncia. Una vegada estem a les xarxes cal saber alimentar-les. Publicar regularment per tenir a l&#8217;audi\u00e8ncia interessada. Cal generar contingut d&#8217;inter\u00e8s i crear empatia amb el p\u00fablic.<\/li>\n<li>Fer \u00fas de xarxes socials no vol dir no tenir privadesa. Per\u00f2 ens exposem i aix\u00f2 anys enrere solament era internament en l&#8217;empresa, ara \u00e9s un m\u00e8tode integrat i segueix en avan\u00e7.<\/li>\n<li>La teva imatge \u00e9s la carta de presentaci\u00f3 dels teus valors, ess\u00e8ncia, car\u00e0cter, etc.<\/li>\n<li>Actualitzaci\u00f3.\u00a0Estar en xarxes socials comporta treball. Si vols que siguin productives t&#8217;aconsellem tractar-la com una activitat m\u00e9s de l&#8217;empresa<\/li>\n<\/ol>\n<p>Linkedin, Twitter, Instagram, Snapchat, Pinterest, YouTube, Facebook,\u00a0sigui quina sigui l&#8217;escollida, la imatge juga un paper fonamental. Evitar de tractar la imatge amb superficialitat i veure-la com a aliada professional, clau i essencial per treure-li el m\u00e0xim rendiment i visibilitat.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00abUna imatge val m\u00e9s que mil palabras\u00bb La majoria de professionals estan en alguna xarxa social, la seva imatge personal \u00e9s observada, valorada i analitzada professionalment segons la xarxa social. Les xarxes socials s\u00f3n un aparador de visibilitat per projectar coneixements, habilitats, compet\u00e8ncies, interessos, etc. Qu\u00e8 cal saber per treure la m\u00e0xima visibilitat professional a [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":4372,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[1958],"class_list":["post-4376","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-general","tag-assessoriaimatgeprofessional-lideralatevaimatge-cartadepresentacio-xarxessocials"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials - Consol Vilar<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials - Consol Vilar\" \/>\n<meta property=\"og:description\" content=\"\u00abUna imatge val m\u00e9s que mil palabras\u00bb La majoria de professionals estan en alguna xarxa social, la seva imatge personal \u00e9s observada, valorada i analitzada professionalment segons la xarxa social. Les xarxes socials s\u00f3n un aparador de visibilitat per projectar coneixements, habilitats, compet\u00e8ncies, interessos, etc. Qu\u00e8 cal saber per treure la m\u00e0xima visibilitat professional a [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/\" \/>\n<meta property=\"og:site_name\" content=\"Consol Vilar\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-18T16:21:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-30T11:04:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/consolvilar.com\/wp-content\/uploads\/2017\/04\/Visibilidad-profesional-a-traves-de-la-imagen-personal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"409\" \/>\n\t<meta property=\"og:image:height\" content=\"373\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ergates Tecnologia SL\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ergates Tecnologia SL\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/\"},\"author\":{\"name\":\"Ergates Tecnologia SL\",\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/#\\\/schema\\\/person\\\/4cceb056bd830c1609de48e671ef6b3f\"},\"headline\":\"Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials\",\"datePublished\":\"2017-04-18T16:21:25+00:00\",\"dateModified\":\"2024-04-30T11:04:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/\"},\"wordCount\":346,\"image\":{\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/consolvilar.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Visibilidad-profesional-a-traves-de-la-imagen-personal.jpg\",\"keywords\":[\"#assessoriaimatgeprofessional #lideralatevaimatge #cartadepresentaci\u00f3 #xarxessocials\"],\"articleSection\":[\"General\"],\"inLanguage\":\"ca\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/\",\"url\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/\",\"name\":\"Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials - Consol Vilar\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/consolvilar.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Visibilidad-profesional-a-traves-de-la-imagen-personal.jpg\",\"datePublished\":\"2017-04-18T16:21:25+00:00\",\"dateModified\":\"2024-04-30T11:04:33+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/#\\\/schema\\\/person\\\/4cceb056bd830c1609de48e671ef6b3f\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/#primaryimage\",\"url\":\"https:\\\/\\\/consolvilar.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Visibilidad-profesional-a-traves-de-la-imagen-personal.jpg\",\"contentUrl\":\"https:\\\/\\\/consolvilar.com\\\/wp-content\\\/uploads\\\/2017\\\/04\\\/Visibilidad-profesional-a-traves-de-la-imagen-personal.jpg\",\"width\":409,\"height\":373},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/visibilidad-profesional-traves-la-imagen-personal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/\",\"name\":\"Consol Vilar\",\"description\":\"Imagen personal y profesional\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/#\\\/schema\\\/person\\\/4cceb056bd830c1609de48e671ef6b3f\",\"name\":\"Ergates Tecnologia SL\",\"sameAs\":[\"http:\\\/\\\/www.ergates.net\"],\"url\":\"https:\\\/\\\/consolvilar.com\\\/ca\\\/author\\\/ergates\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials - Consol Vilar","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/","og_locale":"ca_ES","og_type":"article","og_title":"Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials - Consol Vilar","og_description":"\u00abUna imatge val m\u00e9s que mil palabras\u00bb La majoria de professionals estan en alguna xarxa social, la seva imatge personal \u00e9s observada, valorada i analitzada professionalment segons la xarxa social. Les xarxes socials s\u00f3n un aparador de visibilitat per projectar coneixements, habilitats, compet\u00e8ncies, interessos, etc. Qu\u00e8 cal saber per treure la m\u00e0xima visibilitat professional a [&hellip;]","og_url":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/","og_site_name":"Consol Vilar","article_published_time":"2017-04-18T16:21:25+00:00","article_modified_time":"2024-04-30T11:04:33+00:00","og_image":[{"width":409,"height":373,"url":"https:\/\/consolvilar.com\/wp-content\/uploads\/2017\/04\/Visibilidad-profesional-a-traves-de-la-imagen-personal.jpg","type":"image\/jpeg"}],"author":"Ergates Tecnologia SL","twitter_card":"summary_large_image","twitter_misc":{"Escrit per":"Ergates Tecnologia SL","Temps estimat de lectura":"2 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/#article","isPartOf":{"@id":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/"},"author":{"name":"Ergates Tecnologia SL","@id":"https:\/\/consolvilar.com\/ca\/#\/schema\/person\/4cceb056bd830c1609de48e671ef6b3f"},"headline":"Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials","datePublished":"2017-04-18T16:21:25+00:00","dateModified":"2024-04-30T11:04:33+00:00","mainEntityOfPage":{"@id":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/"},"wordCount":346,"image":{"@id":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/#primaryimage"},"thumbnailUrl":"https:\/\/consolvilar.com\/wp-content\/uploads\/2017\/04\/Visibilidad-profesional-a-traves-de-la-imagen-personal.jpg","keywords":["#assessoriaimatgeprofessional #lideralatevaimatge #cartadepresentaci\u00f3 #xarxessocials"],"articleSection":["General"],"inLanguage":"ca"},{"@type":"WebPage","@id":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/","url":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/","name":"Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials - Consol Vilar","isPartOf":{"@id":"https:\/\/consolvilar.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/#primaryimage"},"image":{"@id":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/#primaryimage"},"thumbnailUrl":"https:\/\/consolvilar.com\/wp-content\/uploads\/2017\/04\/Visibilidad-profesional-a-traves-de-la-imagen-personal.jpg","datePublished":"2017-04-18T16:21:25+00:00","dateModified":"2024-04-30T11:04:33+00:00","author":{"@id":"https:\/\/consolvilar.com\/ca\/#\/schema\/person\/4cceb056bd830c1609de48e671ef6b3f"},"breadcrumb":{"@id":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/#primaryimage","url":"https:\/\/consolvilar.com\/wp-content\/uploads\/2017\/04\/Visibilidad-profesional-a-traves-de-la-imagen-personal.jpg","contentUrl":"https:\/\/consolvilar.com\/wp-content\/uploads\/2017\/04\/Visibilidad-profesional-a-traves-de-la-imagen-personal.jpg","width":409,"height":373},{"@type":"BreadcrumbList","@id":"https:\/\/consolvilar.com\/ca\/visibilidad-profesional-traves-la-imagen-personal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/consolvilar.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Imatge personal, visibilitat professional a trav\u00e9s de les xarxes socials"}]},{"@type":"WebSite","@id":"https:\/\/consolvilar.com\/ca\/#website","url":"https:\/\/consolvilar.com\/ca\/","name":"Consol Vilar","description":"Imagen personal y profesional","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/consolvilar.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Person","@id":"https:\/\/consolvilar.com\/ca\/#\/schema\/person\/4cceb056bd830c1609de48e671ef6b3f","name":"Ergates Tecnologia SL","sameAs":["http:\/\/www.ergates.net"],"url":"https:\/\/consolvilar.com\/ca\/author\/ergates\/"}]}},"_links":{"self":[{"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/posts\/4376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/comments?post=4376"}],"version-history":[{"count":2,"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/posts\/4376\/revisions"}],"predecessor-version":[{"id":18546,"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/posts\/4376\/revisions\/18546"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/media\/4372"}],"wp:attachment":[{"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/media?parent=4376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/categories?post=4376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/consolvilar.com\/ca\/wp-json\/wp\/v2\/tags?post=4376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}